{"id":479,"date":"2020-12-03T10:30:37","date_gmt":"2020-12-03T09:30:37","guid":{"rendered":"https:\/\/www.antonsl.es\/blog\/?p=479"},"modified":"2023-01-10T16:40:39","modified_gmt":"2023-01-10T15:40:39","slug":"ceras-dentales","status":"publish","type":"post","link":"https:\/\/www.antonsl.es\/blog\/ceras-dentales\/","title":{"rendered":"Ceras dentales, tipos y usos"},"content":{"rendered":"<span class=\"rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Tiempo de lectura:<\/span> <span class=\"rt-time\">3<\/span> <span class=\"rt-label rt-postfix\">minutos<\/span><\/span><p><span style=\"font-weight: 400;\">\u00bfConoces lo que son las<\/span><a href=\"https:\/\/www.antonsl.es\/consumibles\/impresion\"><span style=\"font-weight: 400;\"> ceras dentales<\/span><\/a><span style=\"font-weight: 400;\">, as\u00ed como sus tipos y usos? \u00bfNo?\u00a0 Pues no te preocupes porque te vamos a contar todo lo que debes saber acerca de este compuesto de impresi\u00f3n tan utilizado en el sector dental.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Las ceras dentales son un material compuesto por todo tipo de ceras naturales o sint\u00e9ticas, \u00e1cidos, resinas naturales y aceites. Adem\u00e1s, si se quiere, tambi\u00e9n se pueden aplicar distintos pigmentos para darle la coloraci\u00f3n deseada.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Debido a sus caracter\u00edsticas, las ceras dentales, ofrecen una gran cantidad de usos en distintos aspectos odontol\u00f3gicos llevados a cabo durante los procesos con los pacientes.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Algunos de estos trabajos con cera dental son los que, por ejemplo, se encargan de la creaci\u00f3n de encerados o de impresi\u00f3n de la mordida.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En cuanto a la composici\u00f3n de este tipo de ceras, y no te asustes, podemos contar con la extra\u00edda de ciertos insectos, como podr\u00eda ser la de la abeja. Adem\u00e1s de los elementos ya mencionados como pueden ser distintos elementos naturales y la combinaci\u00f3n con otros de car\u00e1cter sint\u00e9tico.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El uso de las ceras dentales es una pr\u00e1ctica que se lleva a cabo debido a que, con el tratamiento de calor adecuado, se puede conseguir un material relativamente el\u00e1stico y moldeable que las convierte en una opci\u00f3n estupenda para ciertos tratamientos.<\/span><\/p>\n<p><a href=\"https:\/\/www.antonsl.es\/consumibles\/impresion\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-821 size-full\" src=\"https:\/\/www.antonsl.es\/blog\/wp-content\/uploads\/2020\/07\/Ceras-Dentales_CTA.png\" alt=\"\" width=\"726\" height=\"135\" srcset=\"https:\/\/www.antonsl.es\/blog\/wp-content\/uploads\/2020\/07\/Ceras-Dentales_CTA.png 726w, https:\/\/www.antonsl.es\/blog\/wp-content\/uploads\/2020\/07\/Ceras-Dentales_CTA-300x56.png 300w\" sizes=\"(max-width: 726px) 100vw, 726px\" \/><\/a><\/p>\n<h2><span style=\"font-weight: 500;\">Clasificaciones y tipos de ceras dnetales u odontol\u00f3gicas<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Una de las ventajas que nos ofrecen las ceras odontol\u00f3gicas es que, en funci\u00f3n de la temperatura que le apliquemos se puede moldear m\u00e1s o menos. Es por eso que existen diferentes clasificaciones, as\u00ed como tipos de cera dental.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Seg\u00fan su clasificaci\u00f3n podemos ver estos 3 ejemplos:<\/span><\/p>\n<h3><span style=\"font-weight: 400;\">Cera para patrones<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Las ceras para patrones ayudan en la construcci\u00f3n y superficies para dentaduras.<\/span><\/p>\n<h3><span style=\"font-weight: 400;\">Cera para procesado<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Las ceras de procesado, o <\/span><a href=\"https:\/\/www.antonsl.es\/consumibles\/laboratorio\/ceras-laboratorio\"><span style=\"font-weight: 400;\">ceras de laboratorio<\/span><\/a><span style=\"font-weight: 400;\">,\u00a0 son fant\u00e1sticas para llevar a cabo procedimientos auxiliares tanto dentro de la cl\u00ednica como en el laboratorio.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-499 size-full\" src=\"https:\/\/www.antonsl.es\/blog\/wp-content\/uploads\/2020\/12\/ceras_dentales_1.jpg\" alt=\"\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.antonsl.es\/blog\/wp-content\/uploads\/2020\/12\/ceras_dentales_1.jpg 700w, https:\/\/www.antonsl.es\/blog\/wp-content\/uploads\/2020\/12\/ceras_dentales_1-300x171.jpg 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/p>\n<h3><span style=\"font-weight: 400;\">Ceras de impresi\u00f3n<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Las <\/span><a href=\"https:\/\/www.antonsl.es\/consumibles\/impresion\/registro-de-mordida-y-ceras\"><span style=\"font-weight: 400;\">ceras de impresi\u00f3n<\/span><\/a><span style=\"font-weight: 400;\">, tal vez de las m\u00e1s utilizadas, son aquellas que se utilizan para obtener moldes de la mordida, com\u00fanmente llamadas impresiones dentales, del paciente.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Si queremos que una cera sea apta para el uso odontol\u00f3gico debe cumplir con una serie de requisitos fundamentales.<\/span><\/p>\n<ol>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Debe tener la capacidad de moldearse seg\u00fan las necesidades y el uso.<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Debe ofrecer baja resistencia al tallado mediante los distintos aparatos que forman el <\/span><a href=\"https:\/\/www.antonsl.es\/consumibles\/instrumental\"><span style=\"font-weight: 400;\">instrumental de cl\u00ednica<\/span><\/a><span style=\"font-weight: 400;\">.<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Debe ser f\u00e1cil de colorear, ya que de ese modo se podr\u00e1 diferenciar del yeso que la retenga.<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Debe ser un elemento compacto. Es decir, una vez separada del molde o recipiente debe mantener estabilidad, sin ser extremadamente r\u00edgida.<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Y por \u00faltimo, y no menos importante, no debe dejar rastro de residuos.<\/span><\/li>\n<\/ol>\n<h2><span style=\"font-weight: 500;\">Usos de las ceras dentales<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">En cuanto a los distintos usos de la cera dental, tal y como hemos comentado con las ceras de impresi\u00f3n se pueden obtener moldes de la mordida del paciente, crear patrones o para tratamientos en el laboratorio.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Adem\u00e1s, tambi\u00e9n son muy frecuentes en aquellas personas que llevan ortodoncia, aplic\u00e1ndose por toda la superficie del tratamiento y creando as\u00ed una capa protectora al tacto.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Tiempo de lectura:<\/span> <span class=\"rt-time\">3<\/span> <span class=\"rt-label rt-postfix\">minutos<\/span><\/span> \u00bfConoces lo que son las ceras dentales, as\u00ed como sus tipos y usos? \u00bfNo?\u00a0 Pues no te preocupes porque te vamos a&hellip;<\/p>\n","protected":false},"author":1,"featured_media":501,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ceras dentales, tipos y usos - Suministros Ant\u00f3n<\/title>\n<meta name=\"description\" content=\"Descubre a trav\u00e9s de nuestro blog dental los distintos tipos y usos que tienen las ceras dentales. Te sorprender\u00e1.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.antonsl.es\/blog\/ceras-dentales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ceras dentales, tipos y usos - Suministros Ant\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Descubre a trav\u00e9s de nuestro blog dental los distintos tipos y usos que tienen las ceras dentales. Te sorprender\u00e1.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.antonsl.es\/blog\/ceras-dentales\/\" \/>\n<meta property=\"og:site_name\" content=\"Suministros Ant\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dentalesanton\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-03T09:30:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-10T15:40:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.antonsl.es\/blog\/wp-content\/uploads\/2020\/12\/ceras_Dentales_Des.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"suministros\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"suministros\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.antonsl.es\/blog\/ceras-dentales\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.antonsl.es\/blog\/ceras-dentales\/\"},\"author\":{\"name\":\"suministros\",\"@id\":\"https:\/\/www.antonsl.es\/blog\/#\/schema\/person\/5ea5016166052ad19d1a960854406c10\"},\"headline\":\"Ceras dentales, tipos y usos\",\"datePublished\":\"2020-12-03T09:30:37+00:00\",\"dateModified\":\"2023-01-10T15:40:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.antonsl.es\/blog\/ceras-dentales\/\"},\"wordCount\":557,\"publisher\":{\"@id\":\"https:\/\/www.antonsl.es\/blog\/#organization\"},\"articleSection\":[\"Divulgaci\u00f3n\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.antonsl.es\/blog\/ceras-dentales\/\",\"url\":\"https:\/\/www.antonsl.es\/blog\/ceras-dentales\/\",\"name\":\"Ceras dentales, tipos y usos - Suministros Ant\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.antonsl.es\/blog\/#website\"},\"datePublished\":\"2020-12-03T09:30:37+00:00\",\"dateModified\":\"2023-01-10T15:40:39+00:00\",\"description\":\"Descubre a trav\u00e9s de nuestro blog dental los distintos tipos y usos que tienen las ceras dentales. Te sorprender\u00e1.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.antonsl.es\/blog\/ceras-dentales\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.antonsl.es\/blog\/ceras-dentales\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.antonsl.es\/blog\/ceras-dentales\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.antonsl.es\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ceras dentales, tipos y usos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.antonsl.es\/blog\/#website\",\"url\":\"https:\/\/www.antonsl.es\/blog\/\",\"name\":\"Blog de Suministros Dentales Ant\u00f3n\",\"description\":\"Suministros dentales\",\"publisher\":{\"@id\":\"https:\/\/www.antonsl.es\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.antonsl.es\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.antonsl.es\/blog\/#organization\",\"name\":\"Blog de Suministros Dentales Ant\u00f3n\",\"url\":\"https:\/\/www.antonsl.es\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.antonsl.es\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.antonsl.es\/blog\/wp-content\/uploads\/2025\/10\/logo-anton.png\",\"contentUrl\":\"https:\/\/www.antonsl.es\/blog\/wp-content\/uploads\/2025\/10\/logo-anton.png\",\"width\":428,\"height\":118,\"caption\":\"Blog de Suministros Dentales Ant\u00f3n\"},\"image\":{\"@id\":\"https:\/\/www.antonsl.es\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dentalesanton\",\"https:\/\/www.instagram.com\/dentalesanton\/\",\"https:\/\/www.linkedin.com\/company\/suministros-dentales-ant-n-s-l-\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.antonsl.es\/blog\/#\/schema\/person\/5ea5016166052ad19d1a960854406c10\",\"name\":\"suministros\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.antonsl.es\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/dd5410d539d8ebd936d3b00b9967b5c2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/dd5410d539d8ebd936d3b00b9967b5c2?s=96&d=mm&r=g\",\"caption\":\"suministros\"},\"url\":\"https:\/\/www.antonsl.es\/blog\/author\/suministros\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ceras dentales, tipos y usos - Suministros Ant\u00f3n","description":"Descubre a trav\u00e9s de nuestro blog dental los distintos tipos y usos que tienen las ceras dentales. Te sorprender\u00e1.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.antonsl.es\/blog\/ceras-dentales\/","og_locale":"es_ES","og_type":"article","og_title":"Ceras dentales, tipos y usos - Suministros Ant\u00f3n","og_description":"Descubre a trav\u00e9s de nuestro blog dental los distintos tipos y usos que tienen las ceras dentales. Te sorprender\u00e1.","og_url":"https:\/\/www.antonsl.es\/blog\/ceras-dentales\/","og_site_name":"Suministros Ant\u00f3n","article_publisher":"https:\/\/www.facebook.com\/dentalesanton","article_published_time":"2020-12-03T09:30:37+00:00","article_modified_time":"2023-01-10T15:40:39+00:00","og_image":[{"width":700,"height":400,"url":"https:\/\/www.antonsl.es\/blog\/wp-content\/uploads\/2020\/12\/ceras_Dentales_Des.jpg","type":"image\/jpeg"}],"author":"suministros","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"suministros","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.antonsl.es\/blog\/ceras-dentales\/#article","isPartOf":{"@id":"https:\/\/www.antonsl.es\/blog\/ceras-dentales\/"},"author":{"name":"suministros","@id":"https:\/\/www.antonsl.es\/blog\/#\/schema\/person\/5ea5016166052ad19d1a960854406c10"},"headline":"Ceras dentales, tipos y usos","datePublished":"2020-12-03T09:30:37+00:00","dateModified":"2023-01-10T15:40:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.antonsl.es\/blog\/ceras-dentales\/"},"wordCount":557,"publisher":{"@id":"https:\/\/www.antonsl.es\/blog\/#organization"},"articleSection":["Divulgaci\u00f3n"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.antonsl.es\/blog\/ceras-dentales\/","url":"https:\/\/www.antonsl.es\/blog\/ceras-dentales\/","name":"Ceras dentales, tipos y usos - Suministros Ant\u00f3n","isPartOf":{"@id":"https:\/\/www.antonsl.es\/blog\/#website"},"datePublished":"2020-12-03T09:30:37+00:00","dateModified":"2023-01-10T15:40:39+00:00","description":"Descubre a trav\u00e9s de nuestro blog dental los distintos tipos y usos que tienen las ceras dentales. Te sorprender\u00e1.","breadcrumb":{"@id":"https:\/\/www.antonsl.es\/blog\/ceras-dentales\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.antonsl.es\/blog\/ceras-dentales\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.antonsl.es\/blog\/ceras-dentales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.antonsl.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Ceras dentales, tipos y usos"}]},{"@type":"WebSite","@id":"https:\/\/www.antonsl.es\/blog\/#website","url":"https:\/\/www.antonsl.es\/blog\/","name":"Blog de Suministros Dentales Ant\u00f3n","description":"Suministros dentales","publisher":{"@id":"https:\/\/www.antonsl.es\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.antonsl.es\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.antonsl.es\/blog\/#organization","name":"Blog de Suministros Dentales Ant\u00f3n","url":"https:\/\/www.antonsl.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.antonsl.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.antonsl.es\/blog\/wp-content\/uploads\/2025\/10\/logo-anton.png","contentUrl":"https:\/\/www.antonsl.es\/blog\/wp-content\/uploads\/2025\/10\/logo-anton.png","width":428,"height":118,"caption":"Blog de Suministros Dentales Ant\u00f3n"},"image":{"@id":"https:\/\/www.antonsl.es\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dentalesanton","https:\/\/www.instagram.com\/dentalesanton\/","https:\/\/www.linkedin.com\/company\/suministros-dentales-ant-n-s-l-\/"]},{"@type":"Person","@id":"https:\/\/www.antonsl.es\/blog\/#\/schema\/person\/5ea5016166052ad19d1a960854406c10","name":"suministros","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.antonsl.es\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/dd5410d539d8ebd936d3b00b9967b5c2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dd5410d539d8ebd936d3b00b9967b5c2?s=96&d=mm&r=g","caption":"suministros"},"url":"https:\/\/www.antonsl.es\/blog\/author\/suministros\/"}]}},"_links":{"self":[{"href":"https:\/\/www.antonsl.es\/blog\/wp-json\/wp\/v2\/posts\/479"}],"collection":[{"href":"https:\/\/www.antonsl.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.antonsl.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.antonsl.es\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.antonsl.es\/blog\/wp-json\/wp\/v2\/comments?post=479"}],"version-history":[{"count":2,"href":"https:\/\/www.antonsl.es\/blog\/wp-json\/wp\/v2\/posts\/479\/revisions"}],"predecessor-version":[{"id":1065,"href":"https:\/\/www.antonsl.es\/blog\/wp-json\/wp\/v2\/posts\/479\/revisions\/1065"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.antonsl.es\/blog\/wp-json\/wp\/v2\/media\/501"}],"wp:attachment":[{"href":"https:\/\/www.antonsl.es\/blog\/wp-json\/wp\/v2\/media?parent=479"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.antonsl.es\/blog\/wp-json\/wp\/v2\/categories?post=479"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.antonsl.es\/blog\/wp-json\/wp\/v2\/tags?post=479"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}